{"id":3770,"date":"2022-09-09T14:08:48","date_gmt":"2022-09-09T17:08:48","guid":{"rendered":"https:\/\/www.cref13.org.br\/cref13\/?p=3770"},"modified":"2022-09-09T14:08:48","modified_gmt":"2022-09-09T17:08:48","slug":"destaque-no-programa-jogo-aberto","status":"publish","type":"post","link":"https:\/\/www.cref13.org.br\/cref13\/destaque-no-programa-jogo-aberto\/","title":{"rendered":"Destaque no Programa Jogo Aberto"},"content":{"rendered":"\n<p>O CREF13\/BA\u00a0foi destaque no Programa Jogo Aberto, da Tv Band Bahia, na tarde de ontem, 08.\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/p\/CiSm4WWs-l6\/\" target=\"_blank\"><strong>Clique aqui<\/strong><\/a>\u00a0e confira a reportagem veiculada no programa sobre a celebra\u00e7\u00e3o ao Dia do Profissional de Educa\u00e7\u00e3o F\u00edsica, que aconteceu no munic\u00edpio de Irec\u00ea no dia 1\u00ba de setembro, e que contou com a efetiva participa\u00e7\u00e3o do presidente do\u00a0Conselho, Rog\u00e9rio Moura.<\/p>\n\n\n\n<p>Al\u00e9m dos servi\u00e7os oferecidos pelo CREF M\u00f3vel, que tamb\u00e9m esteve na cidade, o evento contou com aulas de Zumba e FitDance, Cross Fitness, Teste de glicemia, Aferi\u00e7\u00e3o de Press\u00e3o, Briquedoteca, Muai Thay, Jud\u00f4, Exposi\u00e7\u00e3o de suplementos, Sorteio de Brindes, e da presen\u00e7a das academias da cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O CREF13\/BA\u00a0foi destaque no Programa Jogo Aberto, da Tv Band Bahia, na tarde de ontem, 08.\u00a0Clique aqui\u00a0e confira a reportagem veiculada no programa sobre a celebra\u00e7\u00e3o ao Dia do Profissional de Educa\u00e7\u00e3o F\u00edsica, que aconteceu no munic\u00edpio de Irec\u00ea no dia 1\u00ba de setembro, e que contou com a efetiva participa\u00e7\u00e3o do presidente do\u00a0Conselho, Rog\u00e9rio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/posts\/3770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/comments?post=3770"}],"version-history":[{"count":1,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/posts\/3770\/revisions"}],"predecessor-version":[{"id":3772,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/posts\/3770\/revisions\/3772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/media\/3771"}],"wp:attachment":[{"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/media?parent=3770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/categories?post=3770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cref13.org.br\/cref13\/wp-json\/wp\/v2\/tags?post=3770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}